{"id":1556,"count":1,"description":"","link":"https:\/\/fasterbikes.eu\/en\/tag\/setting-the-pedal-assistance\/","name":"Setting the pedal assistance","slug":"setting-the-pedal-assistance","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Setting the pedal assistance Archive - Fasterbikes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fasterbikes.eu\/en\/tag\/setting-the-pedal-assistance\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Setting the pedal assistance Archive - Fasterbikes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fasterbikes.eu\/en\/tag\/setting-the-pedal-assistance\/\" \/>\n<meta property=\"og:site_name\" content=\"Fasterbikes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/fasterbikes.eu\\\/en\\\/tag\\\/setting-the-pedal-assistance\\\/\",\"url\":\"https:\\\/\\\/fasterbikes.eu\\\/en\\\/tag\\\/setting-the-pedal-assistance\\\/\",\"name\":\"Setting the pedal assistance Archive - Fasterbikes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fasterbikes.eu\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fasterbikes.eu\\\/en\\\/tag\\\/setting-the-pedal-assistance\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fasterbikes.eu\\\/en\\\/tag\\\/setting-the-pedal-assistance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/fasterbikes.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Setting the pedal assistance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fasterbikes.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fasterbikes.eu\\\/en\\\/\",\"name\":\"Fasterbikes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fasterbikes.eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Setting the pedal assistance Archive - Fasterbikes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fasterbikes.eu\/en\/tag\/setting-the-pedal-assistance\/","og_locale":"en_US","og_type":"article","og_title":"Setting the pedal assistance Archive - Fasterbikes","og_url":"https:\/\/fasterbikes.eu\/en\/tag\/setting-the-pedal-assistance\/","og_site_name":"Fasterbikes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fasterbikes.eu\/en\/tag\/setting-the-pedal-assistance\/","url":"https:\/\/fasterbikes.eu\/en\/tag\/setting-the-pedal-assistance\/","name":"Setting the pedal assistance Archive - Fasterbikes","isPartOf":{"@id":"https:\/\/fasterbikes.eu\/en\/#website"},"breadcrumb":{"@id":"https:\/\/fasterbikes.eu\/en\/tag\/setting-the-pedal-assistance\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/fasterbikes.eu\/en\/tag\/setting-the-pedal-assistance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/fasterbikes.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Setting the pedal assistance"}]},{"@type":"WebSite","@id":"https:\/\/fasterbikes.eu\/en\/#website","url":"https:\/\/fasterbikes.eu\/en\/","name":"Fasterbikes","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fasterbikes.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/fasterbikes.eu\/en\/wp-json\/wp\/v2\/tags\/1556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fasterbikes.eu\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/fasterbikes.eu\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/fasterbikes.eu\/en\/wp-json\/wp\/v2\/posts?tags=1556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}